{"id":254746,"date":"2026-03-04T20:20:20","date_gmt":"2026-03-04T18:20:20","guid":{"rendered":"https:\/\/www.juwelier-wagner.at\/unkategorisiert\/creolen-diamanten_sl481-o-rx\/"},"modified":"2026-05-13T03:39:22","modified_gmt":"2026-05-13T01:39:22","slug":"creolen-diamanten_sl481-o-rx","status":"publish","type":"product","link":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/","title":{"rendered":"Starlight Special"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":249831,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[10471,9755,9764,9353,9368,9555],"product_tag":[],"class_list":{"0":"post-254746","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-starlight-special-starlight","7":"product_cat-schmuckart","8":"product_cat-ohrschmuck","9":"product_cat-schmuck","10":"product_cat-wagner-juwelen","11":"product_cat-starlight","12":"pa_jw_material-18-kt-rosegold","13":"pa_jw_schmuckart-ohrschmuck","14":"pa_jw_stone-diamant","16":"first","17":"instock","18":"sold-individually","19":"purchasable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Starlight Special | Juwelier Wagner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:title\" content=\"Starlight Special | Juwelier Wagner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/\" \/>\n<meta property=\"og:site_name\" content=\"Juwelier Wagner\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/juwelierwagnervienna\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:39:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imagedelivery.net\/tS4FWKUjiN9Ay7rpkz3YCA\/c2fbe690-e0e1-40af-af19-8dee096d5800\/w=1014,h=1014,fit=crop\" \/>\n\t<meta property=\"og:image:width\" content=\"1014\" \/>\n\t<meta property=\"og:image:height\" content=\"1014\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/\",\"url\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/\",\"name\":\"Starlight Special | Juwelier Wagner\",\"isPartOf\":{\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.juwelier-wagner.at\/wp-content\/uploads\/SL481.O.RX_F01.png\",\"datePublished\":\"2026-03-04T18:20:20+00:00\",\"dateModified\":\"2026-05-13T01:39:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#primaryimage\",\"url\":\"https:\/\/www.juwelier-wagner.at\/wp-content\/uploads\/SL481.O.RX_F01.png\",\"contentUrl\":\"https:\/\/www.juwelier-wagner.at\/wp-content\/uploads\/SL481.O.RX_F01.png\",\"width\":1014,\"height\":1014},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.juwelier-wagner.at\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.juwelier-wagner.at\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Starlight Special\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.juwelier-wagner.at\/en\/#website\",\"url\":\"https:\/\/www.juwelier-wagner.at\/en\/\",\"name\":\"Juwelier Wagner\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.juwelier-wagner.at\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Starlight Special | Juwelier Wagner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/","og_locale":"en_US","og_title":"Starlight Special | Juwelier Wagner","og_url":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/","og_site_name":"Juwelier Wagner","article_publisher":"https:\/\/facebook.com\/juwelierwagnervienna","article_modified_time":"2026-05-13T01:39:22+00:00","og_image":[{"width":1014,"height":1014,"url":"https:\/\/imagedelivery.net\/tS4FWKUjiN9Ay7rpkz3YCA\/c2fbe690-e0e1-40af-af19-8dee096d5800\/w=1014,h=1014,fit=crop","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/","url":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/","name":"Starlight Special | Juwelier Wagner","isPartOf":{"@id":"https:\/\/www.juwelier-wagner.at\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#primaryimage"},"image":{"@id":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.juwelier-wagner.at\/wp-content\/uploads\/SL481.O.RX_F01.png","datePublished":"2026-03-04T18:20:20+00:00","dateModified":"2026-05-13T01:39:22+00:00","breadcrumb":{"@id":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#primaryimage","url":"https:\/\/www.juwelier-wagner.at\/wp-content\/uploads\/SL481.O.RX_F01.png","contentUrl":"https:\/\/www.juwelier-wagner.at\/wp-content\/uploads\/SL481.O.RX_F01.png","width":1014,"height":1014},{"@type":"BreadcrumbList","@id":"https:\/\/www.juwelier-wagner.at\/en\/schmuck\/wagner-juwelen\/starlight\/starlight-special-starlight\/creolen-diamanten_sl481-o-rx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.juwelier-wagner.at\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.juwelier-wagner.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Starlight Special"}]},{"@type":"WebSite","@id":"https:\/\/www.juwelier-wagner.at\/en\/#website","url":"https:\/\/www.juwelier-wagner.at\/en\/","name":"Juwelier Wagner","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.juwelier-wagner.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/product\/254746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/comments?post=254746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/media\/249831"}],"wp:attachment":[{"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/media?parent=254746"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/product_brand?post=254746"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/product_cat?post=254746"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.juwelier-wagner.at\/en\/wp-json\/wp\/v2\/product_tag?post=254746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}